{"id":3930,"date":"2026-05-06T14:30:06","date_gmt":"2026-05-06T12:30:06","guid":{"rendered":"https:\/\/wisdomize.com\/?page_id=3930"},"modified":"2026-05-06T14:30:06","modified_gmt":"2026-05-06T12:30:06","slug":"imprint-3","status":"publish","type":"page","link":"https:\/\/wisdomize.com\/en\/imprint-3\/","title":{"rendered":"Imprint"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text el_class=&#8221;subtiteltext&#8221;]Imprint[\/vc_column_text][vc_column_text]\n<h1>The fine print in large print<\/h1>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;100px&#8221;][vc_column_text]<strong>Herausgeber<\/strong><\/p>\n<p>Der Herausgeber dieser Website ist:<\/p>\n<p><strong>fund2seed GmbH<\/strong><\/p>\n<p>Frankenh\u00f6he 40<br \/>\n55288 Spiesheim<br \/>\nDeutschland<\/p>\n<p>Email: impressum\u201cat\u201cf2s.lu<\/p>\n<p>LEI: 529900ZAADEON1CQW977<\/p>\n<p>Steuer-ID: DE342315510<\/p>\n<p>Alleiniger Gesch\u00e4ftsf\u00fchrer ist Sven Ulbrich.<br \/>\nfund2seed ist eingetragen beim Amtsgericht Mainz unter der Nummer B.50204.<\/p>\n<p>Die fund2seed GmbH nachfolgend auch \u201e<strong>F2S<\/strong>\u201c.<\/p>\n<p><strong>F2S ist nicht zur nicht zur Anlageberatung erm\u00e4chtigt und spricht keine Empfehlungen f\u00fcr Anleger aus.<\/strong><\/p>\n<hr \/>\n<p><strong>Unsere Gesellschaften<\/strong><\/p>\n<p><strong>fund2index GmbH<\/strong><\/p>\n<p>Schillerstrasse 27<br \/>\n60313 Frankfurt am Main<br \/>\nDeutschland<br \/>\nTelefon: +49 (69) 400 569 981<br \/>\nEmail: impressum\u201cat\u201cf2index.com<\/p>\n<p>LEI: 529900RFNE6WGG7UAQ12<\/p>\n<p>Steuer-ID: DE361166484<\/p>\n<p>Gesch\u00e4ftsf\u00fchrer: Christian Schedling, Sven Ulbrich<br \/>\nfund2index ist eingetragen beim Amtsgericht Frankfurt am Main unter der Nummer HRB 137301<\/p>\n<p><strong>fund2sec S.\u00e0 r.l.<\/strong><\/p>\n<p>46, rue de Pr\u00e9s<br \/>\n5316 Contern<br \/>\nGro\u00dfherzogtum Luxemburg<\/p>\n<p>Email: impressum\u201cat\u201cf2s.lu<\/p>\n<p>LEI: 52990019F6AXLJ4TPK58<\/p>\n<p>TVA: LU33992938<\/p>\n<p>Gesch\u00e4ftsf\u00fchrer der fund2sec: Nadja Knoth \/ Sven Ulbrich<br \/>\nSitz der fund2sec ist Contern im Gro\u00dfherzogtum Luxemburg \/ RCS: B.265552<\/p>\n<p><strong>fund2pac S.\u00e0 r.l.<\/strong><\/p>\n<p>46, rue de Pr\u00e9s<br \/>\n5316 Contern<br \/>\nGro\u00dfherzogtum Luxemburg<\/p>\n<p>Email: impressum\u201cat\u201cf2s.lu<\/p>\n<p>LEI: 52990054X2W2QJPO2K65<\/p>\n<p>TVA: LU34798281<\/p>\n<p>Gesch\u00e4ftsf\u00fchrer der fund2pac: Nadja Knoth \/ Sven Ulbrich<br \/>\nSitz der fund2sec ist Contern im Gro\u00dfherzogtum Luxemburg \/ RCS: B.276093<\/p>\n<p><strong>fund2alpha S.\u00e0 r.l.<\/strong><\/p>\n<p>46, rue de Pr\u00e9s<br \/>\n5316 Contern<br \/>\nGro\u00dfherzogtum Luxemburg<\/p>\n<p>Email: impressum\u201cat\u201cf2s.lu<\/p>\n<p>LEI: 529900IDOMZOMU0DC444<\/p>\n<p>Gesch\u00e4ftsf\u00fchrer der fund2alpha: Nadja Knoth \/ Sven Ulbrich<br \/>\nSitz der fund2alpha ist Contern im Gro\u00dfherzogtum Luxemburg \/ RCS: B.279725<\/p>\n<p><strong>r2y S.\u00e0 r.l.<\/strong><\/p>\n<p>46, rue de Pr\u00e9s<br \/>\n5316 Contern<br \/>\nGro\u00dfherzogtum Luxemburg<\/p>\n<p>Email: impressum\u201cat\u201cf2s.lu<\/p>\n<p>LEI: 52990049MIW5N569A324<\/p>\n<p>TVA: LU35641559<\/p>\n<p>Gesch\u00e4ftsf\u00fchrer der r2y: Nadja Knoth \/ Sven Ulbrich<br \/>\nSitz der r2y ist Contern im Gro\u00dfherzogtum Luxemburg \/ RCS: B.279633<\/p>\n<p><strong>Luxembourg Securities and Derivatives S.\u00e0 r.l. (&#8220;LSAD&#8221;)<\/strong><\/p>\n<p>46, rue de Pr\u00e9s<br \/>\n5316 Contern<br \/>\nGro\u00dfherzogtum Luxemburg<\/p>\n<p>Email: impressum\u201cat\u201cf2s.lu<\/p>\n<p>LEI: 529900P4VW1T49X3ZW67<\/p>\n<p>TVA: LU34078088<\/p>\n<p>Gesch\u00e4ftsf\u00fchrer der LSAD: Nadja Knoth \/ Sven Ulbrich \/ Bj\u00f6rn Recher \/ Thomas Warnecke<br \/>\nSitz der LSAD ist Contern im Gro\u00dfherzogtum Luxemburg \/ RCS: B.264650<\/p>\n<hr \/>\n<p><strong>Aufsichtsbeh\u00f6rde f\u00fcr die fund2index<\/strong><\/p>\n<p>Bundesanstalt f\u00fcr Finanzdienstleistungsaufsicht (BaFin)<br \/>\nGraurheindorfer Stra\u00dfe 108<br \/>\n53117 Bonn, Deutschland<br \/>\nTelefon: +49 (0) 228 4108-0<br \/>\nFax: +49 (0) 228 4108-1550<br \/>\n<a href=\"http:\/\/www.bafin.de\">www.bafin.de<\/a><\/p>\n<p>BaFin-ID: 40035303<\/p>\n<p>Informationen zur Registrierung der f2index finden Sie unter <a href=\"https:\/\/registers.esma.europa.eu\/publication\/details?core=esma_registers_bench_entities&amp;docId=6daf38d7-3164-4dbf-9863-897ba6e938fe\">ESMA Registers (europa.eu)<\/a><\/p>\n<p><strong>Die fund2index ist nicht zur nicht zur Anlageberatung erm\u00e4chtigt und spricht keine Empfehlungen f\u00fcr Anleger aus.<\/strong><\/p>\n<hr \/>\n<p><strong>Kundenbeschwerden<\/strong><\/p>\n<p>Sie k\u00f6nnen sich mit Ihrer Beschwerde \u00fcber verschiedene Wege an uns wenden:<\/p>\n<p><strong>Pers\u00f6nlich:<\/strong> Direkt in allen B\u00fcros der obengenannten Gesellschaften<\/p>\n<p><strong>Telefonisch:<\/strong> unter (+49) 69 400 569 981<\/p>\n<p><strong>E-Mail:<\/strong> beschwerde\u201cat\u201cf2s.lu<\/p>\n<p><strong>Schriftlich:<\/strong> Senden Sie ihre schriftliche Beschwerde bitte an Frank Mayer, c\/o REVCOMP GmbH, Robert-Koch-Strasse 1a, 63225 Langen, Deutschland<\/p>\n<hr \/>\n<p><strong>Rechte an geistigem Eigentum<\/strong><\/p>\n<p>S\u00e4mtliche Warenzeichen, Dienstleistungsmarken oder eingetragenen Warenzeichen sind Eigentum ihrer jeweiligen Inhaber und unterliegen dem deutschen Urheberrecht.<\/p>\n<p>Der Inhalt dieser Website ist durch Copyright, Warenzeichen und andere Formen von Urheberrechten gesch\u00fctzt. Der gesamte Inhalt steht im Besitz und unter der Kontrolle von F2S bzw. der Partei, der die Lieferung des Inhalts zugeschrieben wird. Sofern nicht ausdr\u00fccklich hierin festgelegt, ist nichts auf dieser Website so aufzufassen, als gew\u00e4hre es gem\u00e4\u00df einem Urheberrecht, Patent oder Warenzeichen oder anderen geistigen Eigentumsrechten von F2S oder Dritten Lizenzen oder Rechte.<\/p>\n<p>Jegliche Vervielf\u00e4ltigung von Informationen oder Daten, insbesondere die Benutzung von Texten und Grafiken, erfordert die vorherige Genehmigung durch F2S.<\/p>\n<p>Auf dieser Website ver\u00f6ffentlichte Referenzwerte (Indizes, Zinss\u00e4tze etc) sind, sofern nicht anders angegeben, mindestens 15 Minuten zeitverz\u00f6gert und bleiben (a) das geistige Eigentum der f2index und werden von F2S unter Lizenz ver\u00f6ffentlicht und d\u00fcrfen (b) nicht ohne vorherige schriftliche Zustimmung der f2index oder F2S von Personen, die auf diese Website zugreifen, weiterverbreitet werden.<\/p>\n<hr \/>\n<p><strong>Inhalt und Benutzung dieser Website<\/strong><\/p>\n<p>Diese Website ist nur f\u00fcr Ihren pers\u00f6nlichen und internen Gebrauch bestimmt und darf nicht zu kommerziellen Zwecken (mit oder ohne Gewinnerzielungsabsicht) benutzt werden.<\/p>\n<p>Sie d\u00fcrfen als Benutzer keine Sekund\u00e4rwerke aus den Informationen oder der Software dieser Website verkaufen, kopieren, publizieren, verbreiten, \u00fcbertragen, modifizieren, ver\u00f6ffentlichen, reproduzieren und\/oder erstellen (weder manuell noch unter Verwendung von automatisierten Technologien). Die Vervielf\u00e4ltigung von Informationen oder Daten, insbesondere die Verwendung von Texten, Textteilen oder Bildmaterial bedarf der vorherigen Zustimmung der F2S.<\/p>\n<p>Der Inhalt dieser Website, einschlie\u00dflich Texten, Grafiken, Links und\/oder sonstigen Elementen, wurde anhand von Quellen, Materialien und Systemen erstellt, die als verl\u00e4sslich und genau gelten, und werden Ihnen auf aktueller und verf\u00fcgbarer Basis geliefert.<\/p>\n<p>F2S macht keine Zusicherungen und gibt Ihnen oder Dritten gegen\u00fcber keinerlei ausdr\u00fcckliche, stillschweigende oder gesetzliche Gew\u00e4hr, einschlie\u00dflich unter anderem Zusicherungen und Garantien hinsichtlich der Richtigkeit, Rechtzeitigkeit, Vollst\u00e4ndigkeit, Marktg\u00e4ngigkeit, Eignung f\u00fcr einen bestimmten Zweck, Nichtverletzung der Rechte Dritter und\/oder der Reinheit von Computerviren.<\/p>\n<p>Links zu anderen Websites werden zu Ihrem Nutzen geliefert und sind nicht als Empfehlung derartiger Websites, ihres Inhalts, ihrer Produkte und\/oder Dienstleistungen von F2S oder umgekehrt auszulegen. F2S \u00fcbernimmt keine Haftung f\u00fcr die Inhalte von Websites Dritter (ungeachtet dessen, welche Form diese Inhalte haben), und die Benutzung derartiger Websites Dritter erfolgt auf Ihre eigene Gefahr.<\/p>\n<p>Die F2S ist nicht verantwortlich f\u00fcr Informationen auf Websites, die \u00fcber Verweise auf dieser Website erreicht werden k\u00f6nnen, und \u00fcbernehmen daher keine Haftung f\u00fcr die Inhalte aufseiten Dritter. Dies gilt auch f\u00fcr B\u00f6rsen-, Finanz- und sonstige preissensitive Informationen, die aus Systemen Dritter online in Echtzeit oder zeitversetzt auf diese Websites \u00fcbernommen werden.<\/p>\n<p>Internetsoftware- und \u00dcbertragungsprobleme k\u00f6nnen beim Herunterladen und Anzeigen auf einem Computer des Benutzers unter Umst\u00e4nden zu ungenauen oder unvollst\u00e4ndigen Kopien von Informationen und Materialien f\u00fchren. F2S haftet nicht f\u00fcr Fehler, \u00c4nderungen oder Auslassungen, die bei der \u00dcbertragung oder beim Herunterladen von Informationen oder Materialien auftreten.<\/p>\n<p>F2S versucht, den Inhalt dieser Website zu aktualisieren und seine Richtigkeit sicherzustellen. Eine Haftung oder Garantie f\u00fcr die Aktualit\u00e4t, Richtigkeit und Vollst\u00e4ndigkeit der zur Verf\u00fcgung gestellten Informationen kann vorbehaltlich Vorsatz oder grober Fahrl\u00e4ssigkeit nicht \u00fcbernommen werden.<\/p>\n<p>Trotz der Aus\u00fcbung gr\u00f6\u00dfter Vorsicht k\u00f6nnen sich einige Informationen auf dieser Website seit der letzten Aktualisierung ge\u00e4ndert haben. Ebenso \u00fcbernimmt F2S keine Gew\u00e4hr bzw. Garantie daf\u00fcr, dass diese Website, der Betrieb dieser Website, der Inhalt dieser Website oder der Server, der die Website verf\u00fcgbar macht, fehler- oder virusfrei oder frei von sch\u00e4dlichen Komponenten sind, oder dass Ihre Benutzung dieser Website und ihres Inhalts unterbrechnungsfrei erfolgt.<\/p>\n<hr \/>\n<p><strong>Kein Angebot, keine Beratung<\/strong><\/p>\n<p>Sofern nichts anderes vereinbart ist,<\/p>\n<p>(i) stellen die Inhalte auf diesen Websites weder Werbung noch ein Vertragsangebot oder eine Finanz- oder sonstige Beratung dar. Durch das Vorhalten von Inhalten auf diesen Websites bzw. durch deren Aufruf geht die F2S\u00a0 mit dem User keinerlei vertragliche Beziehungen ein. Diese Websites stellen keinen Ersatz f\u00fcr Beratung in Finanz- oder sonstigen Angelegenheiten dar. Keiner der Inhalte auf diesen Websites ist als Empfehlung zu verstehen, bestimmte Transaktionen einzugehen oder zu unterlassen, ohne zuvor eine die Bed\u00fcrfnisse und die Gesamtsituation des Nutzers ber\u00fccksichtigende individuelle Beratung einzuholen.<\/p>\n<p>Dementsprechend ist nichts auf dieser Website ein Angebot, das vom Nutzer angenommen werden kann in der Art, dass dadurch ohne weiteres Hinzutun der F2S vertragliche Verpflichtungen f\u00fcr die F2S entstehen.<\/p>\n<p>(ii) stellt das Zug\u00e4nglichmachen von Informationen oder Funktionalit\u00e4ten auf dieser Website keinerlei Beratung dar (einschlie\u00dflich, ohne Ausnahme, betreffend die Ausf\u00fchrung von Transaktionen oder jede Art von rechtlicher, steuerlicher oder buchhalterischer Beratung oder Beratung hinsichtlich der Eignung oder Rentabilit\u00e4t von Wertpapieren, Investments oder Transaktionen);<\/p>\n<p>(iii) macht die F2S auf dieser Website lediglich Informationen und Funktionalit\u00e4ten allgemeiner Natur zug\u00e4nglich, die nicht als Finanz-, Rechts-, Steuer- oder sonstige Beratung gedacht sind und nicht Angebot, Aufforderung zum Handel oder Empfehlung von Wertpapieren oder sonstiger Finanzprodukte oder Dienstleistungen sind. Die Informationen, die dem Nutzer auf dieser Website zug\u00e4nglich gemacht werden, k\u00f6nnen sich von denen unterscheiden, die anderen Nutzern oder Kunden der F2S zug\u00e4nglich gemacht werden. Der Nutzer sollte sich nicht ausschlie\u00dflich auf die auf dieser Website zug\u00e4nglich gemachten Informationen verlassen und in jedem Fall zus\u00e4tzlich unabh\u00e4ngigen fachlichen Rat einholen, insbesondere soweit es um seine finanziellen, steuerlichen und \/ oder rechtlichen Bed\u00fcrfnisse geht, bevor er irgendwelche Investmententscheidungen trifft.<\/p>\n<p>Die Website umfasst nicht notwendigerweise alle Kriterien, die f\u00fcr die Zwecke des Nutzers entscheidend sind oder gibt f\u00fcr den Nutzer \u00a0wichtige Aspekte m\u00f6glicherweise nicht auf dem letzten Stand wieder. Neben den auf dieser Website gezeigten Produkten und Dienstleistungen gibt es auf dem Markt weitere Produkte und Dienstleistungen, die f\u00fcr die Zwecke des Nutzers m\u00f6glicherweise besser geeignet sind.<\/p>\n<hr \/>\n<p><strong>Haftungsausschluss<\/strong><\/p>\n<p>F2S haftet in keinem Fall f\u00fcr Sch\u00e4den, einschlie\u00dflich unter anderem direkter oder indirekter, spezieller, zuf\u00e4lliger oder Folgesch\u00e4den, Verlusten oder Kosten, die in Verbindung mit dieser Website und deren Benutzung oder der Unf\u00e4higkeit ihrer Benutzung durch eine Partei oder im Zusammenhang mit der Nichterf\u00fcllung einer Leistung, mit Fehlern, Auslassungen, Unterbrechungen, M\u00e4ngeln, Verz\u00f6gerungen im Betrieb oder der \u00dcbertragung, Computerviren, Leitungs- oder Systemfehlern auftreten, selbst wenn F2S oder ihren Vertretern die M\u00f6glichkeit derartiger Sch\u00e4den, Verluste oder Kosten bekannt war. F2S macht keine Haftungsbeschr\u00e4nkungen oder -ausschl\u00fcsse wo dies gesetzlich untersagt w\u00e4re. Die Benutzung von Hyperlinks zu anderen Internetquellen erfolgt auf eigene Gefahr.<\/p>\n<p>Wenn Sie mit der Website oder deren Inhalt unzufrieden sind, kontaktieren Sie bitte fund2seed GmbH, Frankenh\u00f6he 40, 55288 Spiesheim \u00a0der Rufnummer (+352) 27 69 49 58. Ihre ausschlie\u00dfliche Abhilfe besteht jedoch in jedem Fall darin, die Benutzung dieser Website und deren Inhalt einzustellen.<\/p>\n<hr \/>\n<p><strong>Anspr\u00fcche hinsichtlich Ihrer Benutzung unserer Website<\/strong><\/p>\n<p>Machen Dritte im Zusammenhang mit Ihrer Benutzung dieser Website Schadensersatzanspr\u00fcche gegen F2S geltend, so stimmen Sie hiermit zu, F2S s\u00e4mtliche Verluste, Kosten, Ma\u00dfnahmen, Verfahren, Anspr\u00fcche, Schadensersatzanspr\u00fcche, Aufwendungen (einschlie\u00dflich angemessener Rechtskosten und -geb\u00fchren) oder Verbindlichkeiten, die F2S direkt aufgrund oder infolge Ihrer Missachtung oder Nichtbefolgung dieser Allgemeinen Gesch\u00e4ftsbedingungen und\/oder Ihrer unsachgem\u00e4\u00dfen Benutzung dieser Website entstehen, in voller H\u00f6he zur\u00fcckzuerstatten.<\/p>\n<p>Keine Partei haftet gegen\u00fcber der Gegenpartei f\u00fcr Verluste oder Sch\u00e4den, die der anderen Partei aus einem Grund entstehen, der \u00fcber die angemessene Kontrolle der ersten Partei hinausgeht, einschlie\u00dflich unter anderem Stromausf\u00e4llen.<\/p>\n<hr \/>\n<p><strong>Beschwerdemanagement<\/strong><\/p>\n<p>Sollten wir Ihre Erwartungen nicht erf\u00fcllen, teilen Sie uns dies bitte mit (Kontaktdaten siehe oben). Wir werden uns bem\u00fchen, Ihr Anliegen unverz\u00fcglich, zumindest aber in einem Zeitraum von h\u00f6chstens 4 Wochen nach Erhalt zu kl\u00e4ren und eine gemeinsame L\u00f6sung zu erarbeiten.<\/p>\n<p>Sie k\u00f6nnen uns hierbei unterst\u00fctzen, indem Sie alle f\u00fcr die Kl\u00e4rung des Sachverhalts relevanten Informationen bzw. Unterlagen Ihrer Korrespondenz beif\u00fcgen, um eine effiziente Behandlung Ihres Vorbringens zu gew\u00e4hrleisten. Sollte es zu ungeplanten Verz\u00f6gerungen kommen, erhalten Sie eine Mitteilung. Sie werden w\u00e4hrend der Bearbeitung Ihres Anliegens regelm\u00e4\u00dfig \u00fcber den Stand der Bearbeitung informiert. F\u00fcr Sie als Kunde ist dieser Service kostenfrei.<\/p>\n<hr \/>\n<p><strong>Hinweis zur EU-Prospektverordnung<\/strong><\/p>\n<p>Mit Wirkung am 21. Juli 2019 findet die neue EU Prospektverordnung (Verordnung (EU) 2017\/1129) Anwendung. Kunden sind demnach \u00fcber m\u00f6gliche Ver\u00f6ffentlichung von Prospektnachtr\u00e4gen und die M\u00f6glichkeit von etwaigen Widerrufsrechten Gebrauch zu machen, zu informieren. N\u00e4here Informationen finden Sie unter\u00a0<a href=\"http:\/\/wisdomize.com.w01b411f.kasserver.com\/produkte\/\">http:\/\/wisdomize.com.w01b411f.kasserver.com\/produkte\/<\/a>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;green&#8221; id=&#8221;wisdomize&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text el_class=&#8221;rowheading&#8221;]<em data-line=\"\" data-color=\"#82CDB1\">Knowledge<\/em>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;15px&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h2>Shared knowledge benefits everyone<\/h2>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;15px&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]Wisdomize provides all decision-makers with the knowledge that matters in the world of sustainable finance, in a short and concise manner. We sometimes offer our own opinion, but we always guarantee that our content is independent and non-partisan.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;15px&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;blog&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_post_grid post_type=&#8221;post&#8221; blog_category=&#8221;all&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; pagination=&#8221;none&#8221; columns=&#8221;3&#8243; grid_item_spacing=&#8221;25px&#8221; grid_item_height=&#8221;30vh&#8221; image_size=&#8221;large&#8221; aspect_ratio_image_size=&#8221;yes&#8221; custom_image_aspect_ratio=&#8221;16-9&#8243; image_loading=&#8221;default&#8221; animation=&#8221;none&#8221; heading_tag=&#8221;h3&#8243; category_position=&#8221;default&#8221; display_excerpt=&#8221;yes&#8221; grid_style=&#8221;content_under_image&#8221; card_design=&#8221;yes&#8221; content_under_image_text_align=&#8221;left&#8221; text_color=&#8221;dark&#8221; hover_effect=&#8221;none&#8221; border_radius=&#8221;none&#8221; posts_per_page=&#8221;3&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;right&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; text=&#8221;Article Overview&#8221; url=&#8221;https:\/\/wisdomize.com\/en\/knowledge\/&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221;&#8230;<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3930","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.2 (Yoast SEO v26.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Imprint fund2seed GmbH<\/title>\n<meta name=\"description\" content=\"The fine print in large print: Here you will find the legal notice of fund2seed GmbH, publisher of the Wisdomize website. Find out more now!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wisdomize.com\/en\/imprint-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Imprint fund2seed GmbH | Wisdomize| Wisdomize {\" \/>\n<meta property=\"og:description\" content=\"The fine print in large print: Here you will find the legal notice of fund2seed GmbH, publisher of the Wisdomize website. Find out more now!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wisdomize.com\/en\/imprint-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Wisdomize\" \/>\n<meta property=\"og:image\" content=\"http:\/\/wisdomize.com.w01b411f.kasserver.com\/wp-content\/uploads\/2023\/07\/wisdomize-header_big-1024x469.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Imprint fund2seed GmbH | Wisdomize\" \/>\n<meta name=\"twitter:description\" content=\"The fine print in large print: Here you will find the legal notice of fund2seed GmbH, publisher of the Wisdomize website. Find out more now!\" \/>\n<meta name=\"twitter:image\" content=\"http:\/\/wisdomize.com.w01b411f.kasserver.com\/wp-content\/uploads\/2023\/07\/wisdomize-header_big-1024x469.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wisdomize.com\/en\/imprint-3\/\",\"url\":\"https:\/\/wisdomize.com\/en\/imprint-3\/\",\"name\":\"Imprint fund2seed GmbH\",\"isPartOf\":{\"@id\":\"https:\/\/wisdomize.com\/en\/#website\"},\"datePublished\":\"2026-05-06T12:30:06+00:00\",\"description\":\"The fine print in large print: Here you will find the legal notice of fund2seed GmbH, publisher of the Wisdomize website. Find out more now!\",\"breadcrumb\":{\"@id\":\"https:\/\/wisdomize.com\/en\/imprint-3\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wisdomize.com\/en\/imprint-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wisdomize.com\/en\/imprint-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/wisdomize.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Imprint\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wisdomize.com\/en\/#website\",\"url\":\"https:\/\/wisdomize.com\/en\/\",\"name\":\"Wisdomize\",\"description\":\"Wisdomize your Investments\",\"publisher\":{\"@id\":\"https:\/\/wisdomize.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wisdomize.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/wisdomize.com\/en\/#organization\",\"name\":\"Wisdomize\",\"alternateName\":\"Wisdomize\",\"url\":\"https:\/\/wisdomize.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/wisdomize.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/wisdomize.com.w01b411f.kasserver.com\/wp-content\/uploads\/2023\/07\/Logo-Wisdomize.svg\",\"contentUrl\":\"http:\/\/wisdomize.com.w01b411f.kasserver.com\/wp-content\/uploads\/2023\/07\/Logo-Wisdomize.svg\",\"width\":1,\"height\":1,\"caption\":\"Wisdomize\"},\"image\":{\"@id\":\"https:\/\/wisdomize.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Imprint fund2seed GmbH","description":"The fine print in large print: Here you will find the legal notice of fund2seed GmbH, publisher of the Wisdomize website. Find out more now!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wisdomize.com\/en\/imprint-3\/","og_locale":"en_US","og_type":"article","og_title":"Imprint fund2seed GmbH | Wisdomize| Wisdomize {","og_description":"The fine print in large print: Here you will find the legal notice of fund2seed GmbH, publisher of the Wisdomize website. Find out more now!","og_url":"https:\/\/wisdomize.com\/en\/imprint-3\/","og_site_name":"Wisdomize","og_image":[{"url":"http:\/\/wisdomize.com.w01b411f.kasserver.com\/wp-content\/uploads\/2023\/07\/wisdomize-header_big-1024x469.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Imprint fund2seed GmbH | Wisdomize","twitter_description":"The fine print in large print: Here you will find the legal notice of fund2seed GmbH, publisher of the Wisdomize website. Find out more now!","twitter_image":"http:\/\/wisdomize.com.w01b411f.kasserver.com\/wp-content\/uploads\/2023\/07\/wisdomize-header_big-1024x469.jpg","twitter_misc":{"Est. reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wisdomize.com\/en\/imprint-3\/","url":"https:\/\/wisdomize.com\/en\/imprint-3\/","name":"Imprint fund2seed GmbH","isPartOf":{"@id":"https:\/\/wisdomize.com\/en\/#website"},"datePublished":"2026-05-06T12:30:06+00:00","description":"The fine print in large print: Here you will find the legal notice of fund2seed GmbH, publisher of the Wisdomize website. Find out more now!","breadcrumb":{"@id":"https:\/\/wisdomize.com\/en\/imprint-3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wisdomize.com\/en\/imprint-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wisdomize.com\/en\/imprint-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/wisdomize.com\/en\/"},{"@type":"ListItem","position":2,"name":"Imprint"}]},{"@type":"WebSite","@id":"https:\/\/wisdomize.com\/en\/#website","url":"https:\/\/wisdomize.com\/en\/","name":"Wisdomize","description":"Wisdomize your Investments","publisher":{"@id":"https:\/\/wisdomize.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wisdomize.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/wisdomize.com\/en\/#organization","name":"Wisdomize","alternateName":"Wisdomize","url":"https:\/\/wisdomize.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wisdomize.com\/en\/#\/schema\/logo\/image\/","url":"http:\/\/wisdomize.com.w01b411f.kasserver.com\/wp-content\/uploads\/2023\/07\/Logo-Wisdomize.svg","contentUrl":"http:\/\/wisdomize.com.w01b411f.kasserver.com\/wp-content\/uploads\/2023\/07\/Logo-Wisdomize.svg","width":1,"height":1,"caption":"Wisdomize"},"image":{"@id":"https:\/\/wisdomize.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/wisdomize.com\/en\/wp-json\/wp\/v2\/pages\/3930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wisdomize.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wisdomize.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wisdomize.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/wisdomize.com\/en\/wp-json\/wp\/v2\/comments?post=3930"}],"version-history":[{"count":1,"href":"https:\/\/wisdomize.com\/en\/wp-json\/wp\/v2\/pages\/3930\/revisions"}],"predecessor-version":[{"id":4452,"href":"https:\/\/wisdomize.com\/en\/wp-json\/wp\/v2\/pages\/3930\/revisions\/4452"}],"wp:attachment":[{"href":"https:\/\/wisdomize.com\/en\/wp-json\/wp\/v2\/media?parent=3930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}